{"id":646,"date":"2025-05-15T16:31:05","date_gmt":"2025-05-15T08:31:05","guid":{"rendered":"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/?p=646"},"modified":"2025-06-30T09:25:19","modified_gmt":"2025-06-30T01:25:19","slug":"suntech-launches-st-c360-industrial-cylindrical-uv-printer-for-customization-markets","status":"publish","type":"post","link":"https:\/\/www.suntechprinter.com\/es\/suntech-lanza-la-impresora-uv-cilindrica-industrial-st-c360-para-mercados-de-personalizacion\/","title":{"rendered":"Suntech lanza la impresora UV cil\u00edndrica industrial ST-C360 para mercados de personalizaci\u00f3n"},"content":{"rendered":"<h2>Dise\u00f1ado para regalos y personalizaci\u00f3n: impresi\u00f3n de alta precisi\u00f3n en diversos materiales irregulares<\/h2>\n<p>Suntech ha presentado oficialmente su impresora UV cil\u00edndrica industrial ST-C360 de \u00faltima generaci\u00f3n, que permite la impresi\u00f3n directa en 360\u00b0 sobre materiales como cer\u00e1mica, metal, vidrio y acero inoxidable. Compatible con tazas, termos y envases de cosm\u00e9ticos, es perfecta para regalos personalizados, personalizaci\u00f3n de comercio electr\u00f3nico y tiradas industriales peque\u00f1as. La m\u00e1quina elimina las limitaciones del etiquetado tradicional, ofreciendo una mayor eficiencia y un atractivo visual duradero.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" title=\"Suntech lanza la impresora Uv cil\u00edndrica industrial St-c360 para mercados de personalizaci\u00f3n\" class=\"alignnone size-full wp-image-647\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/2\u3001\u63a8\u51faST-C360\u5de5\u4e1a\u5706\u67f1\u4f53\u6253\u5370\u673a.webp\" alt=\"Suntech lanza la impresora Uv cil\u00edndrica industrial St-c360 para mercados de personalizaci\u00f3n\" width=\"800\" height=\"800\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1ada para regalos y personalizaci\u00f3n: impresi\u00f3n de alta precisi\u00f3n en diversos materiales irregulares Suntech ha presentado oficialmente su impresora UV cil\u00edndrica industrial ST-C360 de \u00faltima generaci\u00f3n, que permite la impresi\u00f3n directa en 360\u00b0 en materiales como cer\u00e1mica, metal, vidrio y acero inoxidable. Compatible con tazas, termos y envases de cosm\u00e9ticos, es perfecta para regalos personalizados, personalizaci\u00f3n de comercio electr\u00f3nico y tiradas industriales peque\u00f1as. [...]<\/p>","protected":false},"author":4,"featured_media":647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/posts\/646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/comments?post=646"}],"version-history":[{"count":0,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/posts\/646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/media\/647"}],"wp:attachment":[{"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/media?parent=646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/categories?post=646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suntechprinter.com\/es\/wp-json\/wp\/v2\/tags?post=646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}