{"id":1147,"date":"2025-05-27T13:18:33","date_gmt":"2025-05-27T05:18:33","guid":{"rendered":"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/?post_type=products&#038;p=1147"},"modified":"2025-09-04T15:31:18","modified_gmt":"2025-09-04T07:31:18","slug":"suntech-digital-cylindrical-printer-for-tumblers-bottles-and-cans","status":"publish","type":"products","link":"https:\/\/www.suntechprinter.com\/fr\/produits\/suntech-digital-cylindrical-printer-for-tumblers-bottles-and-can\/","title":{"rendered":"Suntech Imprimante num\u00e9rique cylindrique pour gobelets, bouteilles et canettes"},"content":{"rendered":"<h2>Toshiba CF3 Digital Cylindrical Printer - Solution d'impression de haute pr\u00e9cision enti\u00e8rement automatique<\/h2>\n<p data-start=\"322\" data-end=\"683\">Le pr\u00e9sent <span style=\"color: #3366ff;\"><strong><a href=\"https:\/\/www.suntechprinter.com\/fr\/categorie-de-produits\/imprimante-cylindrique\/\" style=\"color: #3366ff;\">imprimante cylindrique num\u00e9rique<\/a><\/strong><\/span> est sp\u00e9cialement con\u00e7ue pour les objets courbes tels que les cylindres et les formes coniques. \u00c9quip\u00e9e de buses industrielles Toshiba CF3 de haute pr\u00e9cision, elle est dot\u00e9e d'un syst\u00e8me de chargement et de d\u00e9chargement enti\u00e8rement automatique et d'un module de contr\u00f4le intelligent, ce qui permet une production par lots efficace et stable pour l'impression personnalis\u00e9e de surfaces courbes.<\/p>\n<p data-start=\"685\" data-end=\"1032\">Offrant de multiples options de configuration des couleurs, cette solution d'impression cylindrique num\u00e9rique prend en charge des produits d'une longueur de 80 \u00e0 2800 mm et d'un diam\u00e8tre de 40 \u00e0 120 mm. Elle int\u00e8gre un syst\u00e8me de contr\u00f4le intelligent Siemens PLC et une conception \u00e0 double pression n\u00e9gative. Les composants d'automatisation optionnels pour la manipulation des mat\u00e9riaux r\u00e9duisent consid\u00e9rablement les co\u00fbts de main-d'\u0153uvre.<\/p>\n<p data-start=\"1034\" data-end=\"1358\">Id\u00e9ale pour l'impression en masse d'une grande vari\u00e9t\u00e9 d'articles cylindriques, notamment les gobelets de cola, les gobelets de poussette, les gobelets de bowling, les gobelets en coquille d'\u0153uf, les chopes de bi\u00e8re, les gobelets de caf\u00e9, les bouteilles de sport, les canettes en aluminium, les untopples, les abat-jour et les bouteilles thermos, cette imprimante cylindrique num\u00e9rique offre une pr\u00e9cision d'impression et une efficacit\u00e9 de production haut de gamme.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724754.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"421\" height=\"421\" class=\"wp-image-1153 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h2><strong>Zoomez sur les d\u00e9tails et constatez la qualit\u00e9<\/strong><\/h2>\n<p><strong><\/strong><\/p>\n<h3><strong>1. Chargement et d\u00e9chargement automatiques<\/strong><\/h3>\n<p>La ligne de production automatique, du chargement au d\u00e9chargement, est enti\u00e8rement automatis\u00e9e.<\/p>\n<p>Compl\u00e9tion ind\u00e9pendante, r\u00e9duction des maillons interm\u00e9diaires et am\u00e9lioration de la production<\/p>\n<p>l'efficacit\u00e9, surtout lorsque la surface est plus belle.<\/p>\n<p><img decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724755.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"415\" height=\"406\" class=\"wp-image-1154 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h3><strong>2. Positionnement du cylindre<\/strong><\/h3>\n<p>L'objet du travail est contr\u00f4l\u00e9 rapidement et avec pr\u00e9cision, plac\u00e9 sur l'\u00e9quipement, par<\/p>\n<p>le palier du corps, le maintien de la pi\u00e8ce de serrage, de sorte que la pi\u00e8ce \u00e0 usiner<\/p>\n<p>est fix\u00e9 \u00e0 la position pr\u00e9cise dans l'appareil.<\/p>\n<p><img decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724756.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"418\" height=\"313\" class=\"wp-image-1155 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h3><strong>3. Double pression n\u00e9gative<\/strong><\/h3>\n<p>La pression n\u00e9gative de la couleur blanche est contr\u00f4l\u00e9e s\u00e9par\u00e9ment, ce qui r\u00e9sout efficacement le probl\u00e8me des diff\u00e9rences de viscosit\u00e9 et de pression n\u00e9gative de l'encre blanche.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724757.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"404\" height=\"273\" class=\"wp-image-1156 aligncenter\" \/><\/p>\n<h3><strong><\/strong><strong>4. Bouton de commande<\/strong><\/h3>\n<p>La cl\u00e9 est enti\u00e8rement \u00e9quip\u00e9e, facile \u00e0 manipuler et \u00e0 utiliser, et le bouton d'arr\u00eat d'urgence est plus s\u00fbr.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724758.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"410\" height=\"259\" class=\"wp-image-1157 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h3><strong>5. \u00c9cran tactile Siemens<\/strong><\/h3>\n<p>Avec une gamme compl\u00e8te de fonctions IHM de base, le Lite Panel est<\/p>\n<p>La s\u00e9rie de panneaux d'entr\u00e9e de gamme id\u00e9ale pour les applications IHM simples.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724759.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"457\" height=\"343\" class=\"wp-image-1158 aligncenter\" \/><\/p>\n<h3><strong><\/strong><strong>6. Contr\u00f4le intelligent Siemens PLC<\/strong><\/h3>\n<p>Puissants, compacts et modulaires, bas\u00e9s sur un automate ou un PC, les contr\u00f4leurs SIMATIC<\/p>\n<p>Il peut \u00eatre install\u00e9 dans l'armoire de commande ou directement sur la machine, de sorte qu'il existe un contr\u00f4leur adapt\u00e9 \u00e0 chaque application.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724760.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"538\" height=\"403\" class=\"wp-image-1159 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h2><strong>CHAMP D'APPLICATION<\/strong><\/h2>\n<p><strong>Explication d\u00e9taill\u00e9e de l'imprimante cylindrique num\u00e9rique<\/strong><\/p>\n<p><strong>Applications : <\/strong>Gobelet \u00e0 coca\/voiture d'enfant\/gobelet de poche\/bouilloire r\u00e9frig\u00e9rante\/bouilloire isotherme\/gobelet \u00e0 \u0153ufs\/gobelet \u00e0 bi\u00e8re\/gobelet \u00e0 caf\u00e9\/gobelet \u00e0 eau pour le sport\/gobelet thermos droit, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724761.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"513\" height=\"359\" class=\"wp-image-1160 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h2><strong>Diversit\u00e9 des effets d'impression du ST-H360<\/strong><\/h2>\n<h3>1. Diverses couleurs et sortie stable<\/h3>\n<p>Adoptant la technologie de contr\u00f4le des couleurs ICC, il n'est pas limit\u00e9 aux couleurs de l'image et peut facilement imprimer des couleurs pleines, des d\u00e9grad\u00e9s et d'autres effets.<\/p>\n<p>Un contr\u00f4le pr\u00e9cis des couleurs peut \u00eatre r\u00e9alis\u00e9 au cours du processus de production.<\/p>\n<h3>2. Technologie d'impression en relief<\/h3>\n<p>Le logiciel permet de d\u00e9finir diff\u00e9rents modes, et il est simple et facile \u00e0 comprendre. L'augmentation de la quantit\u00e9 d'encre peut rendre l'effet de relief plus \u00e9vident, l'effet de brillance partielle mettre en \u00e9vidence la stratification, et l'effet de brillance int\u00e9grale r\u00e9sister aux rayures et \u00e0 l'usure.<\/p>\n<p>&nbsp;<\/p>\n<h3>3.360\u00b0 Effet de jonction sans couture<\/h3>\n<p>Le logiciel ajoute un algorithme de jonction sans couture, qui vous permet d'obtenir facilement un effet de jonction sans couture apr\u00e8s avoir d\u00e9fini la taille. Il est facile \u00e0 utiliser et permet d'obtenir un effet stup\u00e9fiant.<\/p>\n<h3>4. Applications polyvalentes et forte adh\u00e9rence<\/h3>\n<p>Prend en charge une grande vari\u00e9t\u00e9 de mat\u00e9riaux d'impression, tels que la peinture givr\u00e9e\/lisse, l'acier inoxydable, le plastique, le bambou, la c\u00e9ramique, le bois, etc. L'adh\u00e9rence de l'impression est donc enti\u00e8rement garantie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724762.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"541\" height=\"323\" class=\"wp-image-1161 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h2><strong>R\u00e9sultats d'impression de haute qualit\u00e9<\/strong><\/h2>\n<p>Diverses solutions de configuration de l'encre<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" src=\"https:\/\/20250423wcsvv7.v3-site.adwebcloud.com\/wp-content\/uploads\/2025\/05\/\u56fe\u724763.jpg\" alt=\"Suntech Imprimante num\u00e9rique cylindrique 360 degr\u00e9s pour bouteilles Ramblers Tumbler Imprimante Uv avec bo\u00eetes en aluminium Cmykwv\" width=\"553\" height=\"393\" class=\"size-full wp-image-1162 aligncenter\" \/><\/p>\n<p><strong><\/strong><\/p>\n<h2><strong>Un service de qualit\u00e9<\/strong><\/h2>\n<p><strong>D\u00e9pannage : <\/strong>L'entreprise a envoy\u00e9 des ing\u00e9nieurs apr\u00e8s-vente pour r\u00e9soudre le probl\u00e8me et reprendre une production normale d\u00e8s que possible.<\/p>\n<p><strong>Suivi des services : <\/strong>Prendre r\u00e9guli\u00e8rement l'initiative de rendre visite aux clients ; comprendre l'utilisation de l'\u00e9quipement, \u00e9couter les suggestions des clients et donner des conseils techniques, et faire des enregistrements.<\/p>\n<p><strong>Service Consulting : <\/strong>L'\u00e9quipe d'ing\u00e9nieurs professionnels du service apr\u00e8s-vente adopte une vari\u00e9t\u00e9 de m\u00e9thodes de service pour fournir un service en ligne 7*24 heures \u00e0 temps plein.<\/p>\n<p><strong>Garantie de service : <\/strong>L'\u00e9quipement est assorti d'une garantie gratuite d'un an et d'un service d'entretien \u00e0 vie, conform\u00e9ment \u00e0 la norme.<\/p>","protected":false},"excerpt":{"rendered":"<p>L'imprimante cylindrique UV CF3 de Toshiba est un syst\u00e8me de production robuste con\u00e7u pour les applications industrielles exigeantes. Con\u00e7ue pour les objets cylindriques\/coniques (bo\u00eetes en aluminium, flacons en verre, gobelets isothermes, tubes cosm\u00e9tiques), elle exploite la t\u00eate d'impression pi\u00e9zo\u00e9lectrique industrielle CF3 de Toshiba et le s\u00e9chage UV-LED haute puissance pour produire des impressions ultra-pr\u00e9cises de 1200 dpi sur des substrats difficiles tels que les m\u00e9taux rev\u00eatus, le verre borosilicat\u00e9 et les plastiques de qualit\u00e9 m\u00e9dicale. Avec une pr\u00e9cision de rep\u00e9rage de \u00b10,05 mm<\/p>","protected":false},"featured_media":1770,"template":"","adweb_product_categories":[54,19],"adweb_product_tags":[70,73,72,71],"class_list":["post-1147","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-cylinder-printer-with-toshiba-printhead","adweb_product_cat-cylindrical-printer","adweb_product_tag-bottle-printing-machine","adweb_product_tag-eggshell-cup-printing-machine","adweb_product_tag-ice-king-cup-printing-machine","adweb_product_tag-thermos-custom-print"],"gallery":[1758,1728],"order":"0","acf":[],"_links":{"self":[{"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/adweb_products\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/media\/1770"}],"wp:attachment":[{"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/media?parent=1147"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/adweb_product_categories?post=1147"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.suntechprinter.com\/fr\/wp-json\/wp\/v2\/adweb_product_tags?post=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}